{"id":35,"date":"2024-03-06T21:34:56","date_gmt":"2024-03-06T20:34:56","guid":{"rendered":"https:\/\/enterateconalfredocisneros.com\/test\/?p=35"},"modified":"2024-03-06T23:16:07","modified_gmt":"2024-03-06T22:16:07","slug":"5-razones-para-seguir-usando-mascarilla-aun-despues-de-vacunarse","status":"publish","type":"post","link":"https:\/\/enterateconmarielavaldivia.com\/noticias\/2024\/03\/06\/5-razones-para-seguir-usando-mascarilla-aun-despues-de-vacunarse\/","title":{"rendered":"5 razones para seguir usando mascarilla a\u00fan despu\u00e9s de vacunarse."},"content":{"rendered":"\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/enterateconalfredocisneros.com\/noticias\/wp-content\/uploads\/2024\/03\/N6-L-1024x522.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>A\u00fan el final de la pandemia no est\u00e1 cerca. Incluso con la llegada de la vacuna conta la COVID-19, se deben seguir manteniendo las medidas de protecci\u00f3n y bioseguridad. Te damos 5 razones para hacerlo:<\/p>\n\n\n\n<ol>\n<li>Protecci\u00f3n adicional: Aunque las vacunas sean muy eficaces, estas no proveen un 100% de protecci\u00f3n contra el virus.<\/li>\n\n\n\n<li>Prevenir la propagaci\u00f3n: a\u00fan existe informaci\u00f3n que no sabemos sobre el virus. Por ejemplo, los cient\u00edficos no han determinado si luego de vacunarse, la persona a\u00fan puede transmitir el virus.<\/li>\n\n\n\n<li>Tiempo de reacci\u00f3n: las vacunas no nos protegen inmediatamente. El organismo necesita tiempo para desarrollar los anticuerpos necesarios para luchar contra la enfermedad.<\/li>\n\n\n\n<li>Personas vulnerables: si perteneces al grupo de personas con enfermedades preexistentes o vives con alguno, las vacunas a\u00fan no demuestran efectividad para estos casos.<\/li>\n\n\n\n<li>Protecci\u00f3n contra nuevas variantes: los tapabocas son m\u00e1s efectivos en contra de cualquier mutaci\u00f3n o variante nueva del coronavirus.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>A\u00fan el final de la pandemia no est\u00e1 cerca. Incluso con la llegada de la vacuna conta la COVID-19, se deben seguir manteniendo las medidas de protecci\u00f3n y bioseguridad. Te damos 5 razones para hacerlo: Protecci\u00f3n adicional: Aunque las vacunas sean muy eficaces, estas no proveen un 100% de protecci\u00f3n contra el virus. Prevenir la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":38,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,1],"tags":[],"_links":{"self":[{"href":"https:\/\/enterateconmarielavaldivia.com\/noticias\/wp-json\/wp\/v2\/posts\/35"}],"collection":[{"href":"https:\/\/enterateconmarielavaldivia.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enterateconmarielavaldivia.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enterateconmarielavaldivia.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/enterateconmarielavaldivia.com\/noticias\/wp-json\/wp\/v2\/comments?post=35"}],"version-history":[{"count":3,"href":"https:\/\/enterateconmarielavaldivia.com\/noticias\/wp-json\/wp\/v2\/posts\/35\/revisions"}],"predecessor-version":[{"id":41,"href":"https:\/\/enterateconmarielavaldivia.com\/noticias\/wp-json\/wp\/v2\/posts\/35\/revisions\/41"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enterateconmarielavaldivia.com\/noticias\/wp-json\/wp\/v2\/media\/38"}],"wp:attachment":[{"href":"https:\/\/enterateconmarielavaldivia.com\/noticias\/wp-json\/wp\/v2\/media?parent=35"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enterateconmarielavaldivia.com\/noticias\/wp-json\/wp\/v2\/categories?post=35"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enterateconmarielavaldivia.com\/noticias\/wp-json\/wp\/v2\/tags?post=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}